{"id":762,"count":1,"description":"","link":"https:\/\/discosdeluxe.com\/en\/music\/artists\/baron-rojo-en\/","name":"Baron Rojo","slug":"baron-rojo-en","taxonomy":"product_cat","parent":731,"meta":[],"menu_order":0,"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Baron Rojo - Online record and vinyl store, Discos Deluxe<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/discosdeluxe.com\/en\/music\/artists\/baron-rojo-en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Baron Rojo - Online record and vinyl store, Discos Deluxe\" \/>\n<meta property=\"og:url\" content=\"https:\/\/discosdeluxe.com\/en\/music\/artists\/baron-rojo-en\/\" \/>\n<meta property=\"og:site_name\" content=\"Online record and vinyl store, Discos Deluxe\" \/>\n<meta property=\"og:image\" content=\"https:\/\/discosdeluxe.com\/wp-content\/uploads\/2021\/05\/logo-discos-deluxe.png\" \/>\n\t<meta property=\"og:image:width\" content=\"657\" \/>\n\t<meta property=\"og:image:height\" content=\"200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/discosdeluxe.com\\\/en\\\/music\\\/artists\\\/baron-rojo-en\\\/\",\"url\":\"https:\\\/\\\/discosdeluxe.com\\\/en\\\/music\\\/artists\\\/baron-rojo-en\\\/\",\"name\":\"Baron Rojo - Online record and vinyl store, Discos Deluxe\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/discosdeluxe.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/discosdeluxe.com\\\/en\\\/music\\\/artists\\\/baron-rojo-en\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/discosdeluxe.com\\\/en\\\/music\\\/artists\\\/baron-rojo-en\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/discosdeluxe.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Artists\",\"item\":\"https:\\\/\\\/discosdeluxe.com\\\/en\\\/music\\\/artists\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Baron Rojo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/discosdeluxe.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/discosdeluxe.com\\\/en\\\/\",\"name\":\"Tienda de discos y vinilos online, Discos Deluxe\",\"description\":\"Deluxe Records, your vinyl store, buy online. Find all the new music, rarities, LPs, 7\\\" singles, limited editions, ...\",\"publisher\":{\"@id\":\"https:\\\/\\\/discosdeluxe.com\\\/en\\\/#organization\"},\"alternateName\":\"Discos Deluxe\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/discosdeluxe.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/discosdeluxe.com\\\/en\\\/#organization\",\"name\":\"Discos Deluxe\",\"url\":\"https:\\\/\\\/discosdeluxe.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/discosdeluxe.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/discosdeluxe.com\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/logo-discos-deluxe.png\",\"contentUrl\":\"https:\\\/\\\/discosdeluxe.com\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/logo-discos-deluxe.png\",\"width\":657,\"height\":200,\"caption\":\"Discos Deluxe\"},\"image\":{\"@id\":\"https:\\\/\\\/discosdeluxe.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/DiscosDeluxe\\\/\",\"https:\\\/\\\/www.instagram.com\\\/discosdeluxemusic\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Baron Rojo - Online record and vinyl store, Discos Deluxe","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/discosdeluxe.com\/en\/music\/artists\/baron-rojo-en\/","og_locale":"en_US","og_type":"article","og_title":"Baron Rojo - Online record and vinyl store, Discos Deluxe","og_url":"https:\/\/discosdeluxe.com\/en\/music\/artists\/baron-rojo-en\/","og_site_name":"Online record and vinyl store, Discos Deluxe","og_image":[{"width":657,"height":200,"url":"https:\/\/discosdeluxe.com\/wp-content\/uploads\/2021\/05\/logo-discos-deluxe.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/discosdeluxe.com\/en\/music\/artists\/baron-rojo-en\/","url":"https:\/\/discosdeluxe.com\/en\/music\/artists\/baron-rojo-en\/","name":"Baron Rojo - Online record and vinyl store, Discos Deluxe","isPartOf":{"@id":"https:\/\/discosdeluxe.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/discosdeluxe.com\/en\/music\/artists\/baron-rojo-en\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/discosdeluxe.com\/en\/music\/artists\/baron-rojo-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/discosdeluxe.com\/en\/"},{"@type":"ListItem","position":2,"name":"Artists","item":"https:\/\/discosdeluxe.com\/en\/music\/artists\/"},{"@type":"ListItem","position":3,"name":"Baron Rojo"}]},{"@type":"WebSite","@id":"https:\/\/discosdeluxe.com\/en\/#website","url":"https:\/\/discosdeluxe.com\/en\/","name":"Tienda de discos y vinilos online, Discos Deluxe","description":"Deluxe Records, your vinyl store, buy online. Find all the new music, rarities, LPs, 7\" singles, limited editions, ...","publisher":{"@id":"https:\/\/discosdeluxe.com\/en\/#organization"},"alternateName":"Discos Deluxe","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/discosdeluxe.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/discosdeluxe.com\/en\/#organization","name":"Discos Deluxe","url":"https:\/\/discosdeluxe.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/discosdeluxe.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/discosdeluxe.com\/wp-content\/uploads\/2021\/05\/logo-discos-deluxe.png","contentUrl":"https:\/\/discosdeluxe.com\/wp-content\/uploads\/2021\/05\/logo-discos-deluxe.png","width":657,"height":200,"caption":"Discos Deluxe"},"image":{"@id":"https:\/\/discosdeluxe.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/DiscosDeluxe\/","https:\/\/www.instagram.com\/discosdeluxemusic\/"]}]}},"_links":{"self":[{"href":"https:\/\/discosdeluxe.com\/en\/wp-json\/wp\/v2\/product_cat\/762","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/discosdeluxe.com\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/discosdeluxe.com\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/discosdeluxe.com\/en\/wp-json\/wp\/v2\/product_cat\/731"}],"wp:post_type":[{"href":"https:\/\/discosdeluxe.com\/en\/wp-json\/wp\/v2\/product?product_cat=762"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}